{"id":9179,"count":2,"description":"","link":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/","name":"Bestowed","slug":"bestowed","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bestowed Archives - Ghanamma.com<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bestowed Archives - Ghanamma.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/\" \/>\n<meta property=\"og:site_name\" content=\"Ghanamma.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/tag\\\/bestowed\\\/\",\"url\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/tag\\\/bestowed\\\/\",\"name\":\"Bestowed Archives - Ghanamma.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/tag\\\/bestowed\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/tag\\\/bestowed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bestowed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/#website\",\"url\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/\",\"name\":\"Ghanamma.com\",\"description\":\"News In South Africa - Latest South Africa News Headlines\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ghanamma.com\\\/za\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bestowed Archives - Ghanamma.com","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Bestowed Archives - Ghanamma.com","og_url":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/","og_site_name":"Ghanamma.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/","url":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/","name":"Bestowed Archives - Ghanamma.com","isPartOf":{"@id":"https:\/\/www.ghanamma.com\/za\/#website"},"breadcrumb":{"@id":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ghanamma.com\/za\/tag\/bestowed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ghanamma.com\/za\/"},{"@type":"ListItem","position":2,"name":"Bestowed"}]},{"@type":"WebSite","@id":"https:\/\/www.ghanamma.com\/za\/#website","url":"https:\/\/www.ghanamma.com\/za\/","name":"Ghanamma.com","description":"News In South Africa - Latest South Africa News Headlines","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ghanamma.com\/za\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ghanamma.com\/za\/wp-json\/wp\/v2\/tags\/9179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ghanamma.com\/za\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ghanamma.com\/za\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ghanamma.com\/za\/wp-json\/wp\/v2\/posts?tags=9179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}